{"id":22564,"date":"2025-07-11T12:00:09","date_gmt":"2025-07-11T10:00:09","guid":{"rendered":"https:\/\/www.farmaindustria.es\/web\/?p=22564"},"modified":"2025-07-24T08:42:03","modified_gmt":"2025-07-24T06:42:03","slug":"nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario","status":"publish","type":"post","link":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/","title":{"rendered":"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario"},"content":{"rendered":"<div id=\"attachment_22567\" style=\"width: 845px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-22567\" class=\"wp-image-22567 size-full\" src=\"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1.jpg\" alt=\"Representantes de Farmaindustria, Facme, Mujeres en Farma junto al secretario de Estado de Sanidad, Javier Padilla, y la comisionada del PERTE de Salud de Vanguardia, Raquel Yotti.\" width=\"835\" height=\"480\" srcset=\"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1.jpg 835w, https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1-300x172.jpg 300w, https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1-768x441.jpg 768w, https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1-313x180.jpg 313w, https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1-190x109.jpg 190w, https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1-306x175.jpg 306w, https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1-50x29.jpg 50w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/a><p id=\"caption-attachment-22567\" class=\"wp-caption-text\">Representantes de Farmaindustria, Facme, Mujeres en Farma junto al secretario de Estado de Sanidad, Javier Padilla, y la comisionada del PERTE de Salud de Vanguardia, Raquel Yotti.<\/p><\/div>\n<p>A pesar de los avances de los \u00faltimos a\u00f1os, a\u00fan persisten importantes brechas de g\u00e9nero en posiciones de<strong> liderazgo<\/strong> y en la participaci\u00f3n de las mujeres en espacios de <strong>toma de decisiones<\/strong>, foros acad\u00e9micos, cient\u00edficos y empresariales. Desde este punto de partida y el del compromiso del sector salud con la igualdad de g\u00e9nero, nace #EnSaludNoSinMujeres.<\/p>\n<p>Una iniciativa impulsada por Farmaindustria junto a la Federaci\u00f3n de Asociaciones Cient\u00edfico M\u00e9dicas Espa\u00f1olas (Facme) y Mujeres en Farma. Las tres entidades, en colaboraci\u00f3n con el Ministerio de Sanidad, se han unido para impulsar el liderazgo femenino y la visibilidad de las mujeres en todos los foros, comit\u00e9s, congresos y eventos vinculados al sector salud.<\/p>\n<p>La iniciativa se ha presentado este viernes en el Ministerio de Sanidad con la presencia del secretario de Estado de Sanidad, Javier Padilla; la comisionada del PERTE para la Salud de Vanguardia, Raquel Yotti, as\u00ed como los representantes de las organizaciones impulsoras, de compa\u00f1\u00edas farmac\u00e9uticas y biotecnol\u00f3gicas, sociedades cient\u00edficas y m\u00e9dicas, asociaciones de pacientes, <em>think tanks<\/em> y ONG del \u00e1mbito de la salud, as\u00ed como medios de comunicaci\u00f3n.<\/p>\n<p>Padilla ha explicado el compromiso de su Ministerio con la Igualdad y la presencia de mujeres en los \u00e1mbitos de representaci\u00f3n, donde a\u00fan queda camino por recorrer. \u201cTenemos que potenciar el <strong>compromiso p\u00fablico con el <a href=\"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/03\/07\/las-mujeres-ocupan-el-25-de-las-direcciones-generales-en-la-industria-farmaceutica-innovadora-el-triple-que-la-media-de-las-companias-del-ibex35\/\">fomento de la presencia de mujeres<\/a><\/strong> en el \u00e1mbito de la salud\u201d, ha incidido.<\/p>\n<p>La presidenta de Farmaindustria y directora general de Amgen en Espa\u00f1a, Fina Llad\u00f3s Canela, ha mostrado su satisfacci\u00f3n con el lanzamiento de la iniciativa: \u201cEn la industria farmac\u00e9utica estamos convencidos de que la igualdad no es solo un principio \u00e9tico esencial, sino tambi\u00e9n un <strong>motor de progreso, mejora y sostenibilidad<\/strong> para nuestras organizaciones. En este sentido, creemos que #EnSaludNoSinMujeres es una herramienta ideal para ayudarnos a<strong> influir, inspirar y transformar la sociedad<\/strong>\u201d.<\/p>\n<p>La iniciativa se ha presentado en una mesa redonda en la que ha participado el director general de Farmaindustria, Juan Yermo junto a Pilar Garrido y Pilar L\u00f3pez Garc\u00eda, representantes de Womeds\/Facme y Elena \u00c1lvarez, presidenta de Mujeres en Farma. Yermo ha recordado que en la industria farmac\u00e9utica las mujeres representan el 56% de las plantillas, el 45% de los Comit\u00e9s de Direcci\u00f3n y una de cada cuatro direcciones generales. Una cifra que supone el triple de la media de las compa\u00f1\u00edas del IBEX-35. En el caso de la Junta Directiva de Farmaindustria, que componen 36 compa\u00f1\u00edas farmac\u00e9uticas innovadoras, la cifra es superior y alcanza en la actualidad el 44%. \u201cDesde Farmaindustria sabemos que esto no es fruto de la casualidad, sino de un <strong>trabajo de nuestras compa\u00f1\u00edas para seguir avanzando hacia la igualdad<\/strong>. Y por ello nos parecen tan importantes iniciativas como \u00e9sta: es necesario promover la presencia y el liderazgo de las mujeres en todos los \u00e1mbitos de la esfera p\u00fablica y, por supuesto, promover pol\u00edticas que lo fomenten\u201d, ha destacado Yermo.<\/p>\n<p>La iniciativa apela al aumento de la representaci\u00f3n de las mujeres en los espacios con poder de decisi\u00f3n y para ello, plantea un manifiesto con siete peticiones para que sean tenidas en cuenta por todos los agentes del sector.<\/p>\n<ol>\n<li>Promover el <strong>liderazgo, participaci\u00f3n, presencia y visibilidad<\/strong> de la mujer desde la alta direcci\u00f3n en todos los \u00e1mbitos de la salud.<\/li>\n<li>Promover <strong>pol\u00edticas p\u00fablicas<\/strong> que impulsen la participaci\u00f3n y el liderazgo de la mujer, en especial la formaci\u00f3n e informaci\u00f3n en equidad e inclusi\u00f3n en todos los centros de trabajo del sector.<\/li>\n<li>Presencia de mujeres en <strong>grupos t\u00e9cnicos y cient\u00edficos, foros, conferencias, congresos<\/strong> o cualquier otro espacio de la esfera p\u00fablica del sector salud con el fin de que las mujeres est\u00e1n representadas de forma equitativa en estos espacios que condicionan su desarrollo profesional.<\/li>\n<li>Compromiso de las entidades del sector salud para asegurar la presencia de mujeres en los <strong>paneles de expertos <\/strong>o profesionales que se establezcan para la realizaci\u00f3n de actividades cient\u00edficas, de investigaci\u00f3n, organizativas, docentes o divulgativas en salud, con una distribuci\u00f3n basada en m\u00e9ritos y tambi\u00e9n m\u00e1s equitativa en cuanto al g\u00e9nero.<\/li>\n<li><strong>Rechazo<\/strong> a la participaci\u00f3n en eventos sobre el sector Salud, de m\u00e1s de dos ponentes, donde <strong>no se haya contado con, al menos, una mujer<\/strong> en calidad de experta.<\/li>\n<li>Incluir en los formularios de acreditaci\u00f3n de formaci\u00f3n continuada del Sistema Nacional de Salud (SNS) <strong>un apartado de g\u00e9nero que incremente el valor del proyecto<\/strong>.<\/li>\n<li>Paridad de g\u00e9nero en los materiales como <strong>fotos, materiales promocionales y de difusi\u00f3n <\/strong>que reflejen la realidad del sector, donde las mujeres somos mayor\u00eda.<\/li>\n<\/ol>\n<p><a href=\"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/ESNSM_11.07.25.pdf\">M\u00e1s informaci\u00f3n de la iniciativa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de los avances de los \u00faltimos a\u00f1os, a\u00fan persisten importantes brechas de g\u00e9nero en posiciones de liderazgo y en la participaci\u00f3n de las mujeres en espacios de toma de decisiones, foros acad\u00e9micos, cient\u00edficos y empresariales. Desde este punto de partida y el del compromiso del sector salud con la igualdad de g\u00e9nero, nace  <a href=\"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/\" class=\"read-more\">&hellip;<\/a><\/p>\n","protected":false},"author":21,"featured_media":22567,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-22564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tema-igualdad","area-comunicacion","geografica-espana","organismo-farmaindustria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario - FarmaIndustria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario - FarmaIndustria\" \/>\n<meta property=\"og:description\" content=\"A pesar de los avances de los \u00faltimos a\u00f1os, a\u00fan persisten importantes brechas de g\u00e9nero en posiciones de liderazgo y en la participaci\u00f3n de las mujeres en espacios de toma de decisiones, foros acad\u00e9micos, cient\u00edficos y empresariales. Desde este punto de partida y el del compromiso del sector salud con la igualdad de g\u00e9nero, nace &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/\" \/>\n<meta property=\"og:site_name\" content=\"FarmaIndustria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Farmaindustria\/730634013647836?ref=hl\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-11T10:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-24T06:42:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristina Castro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FarmaIndustria\" \/>\n<meta name=\"twitter:site\" content=\"@FarmaIndustria\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristina Castro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/\"},\"author\":{\"name\":\"Cristina Castro\",\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/#\\\/schema\\\/person\\\/77de9caeaf35fd35feb9dec730e79595\"},\"headline\":\"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario\",\"datePublished\":\"2025-07-11T10:00:09+00:00\",\"dateModified\":\"2025-07-24T06:42:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/\"},\"wordCount\":858,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/En-salud-no-sin-mujeres1.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/\",\"url\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/\",\"name\":\"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario - FarmaIndustria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/En-salud-no-sin-mujeres1.jpg\",\"datePublished\":\"2025-07-11T10:00:09+00:00\",\"dateModified\":\"2025-07-24T06:42:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/#\\\/schema\\\/person\\\/77de9caeaf35fd35feb9dec730e79595\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/En-salud-no-sin-mujeres1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/En-salud-no-sin-mujeres1.jpg\",\"width\":835,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/2025\\\/07\\\/11\\\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/\",\"name\":\"FarmaIndustria\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/#\\\/schema\\\/person\\\/77de9caeaf35fd35feb9dec730e79595\",\"name\":\"Cristina Castro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aca4ecc9f65b97ba4366a217870b7ab4201d8e8f678c45221d982b892ff1cd7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aca4ecc9f65b97ba4366a217870b7ab4201d8e8f678c45221d982b892ff1cd7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aca4ecc9f65b97ba4366a217870b7ab4201d8e8f678c45221d982b892ff1cd7c?s=96&d=mm&r=g\",\"caption\":\"Cristina Castro\"},\"url\":\"https:\\\/\\\/www.farmaindustria.es\\\/web\\\/prensa\\\/notas-de-prensa\\\/author\\\/ccastro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario - FarmaIndustria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/","og_locale":"es_ES","og_type":"article","og_title":"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario - FarmaIndustria","og_description":"A pesar de los avances de los \u00faltimos a\u00f1os, a\u00fan persisten importantes brechas de g\u00e9nero en posiciones de liderazgo y en la participaci\u00f3n de las mujeres en espacios de toma de decisiones, foros acad\u00e9micos, cient\u00edficos y empresariales. Desde este punto de partida y el del compromiso del sector salud con la igualdad de g\u00e9nero, nace &hellip;","og_url":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/","og_site_name":"FarmaIndustria","article_publisher":"https:\/\/www.facebook.com\/pages\/Farmaindustria\/730634013647836?ref=hl","article_published_time":"2025-07-11T10:00:09+00:00","article_modified_time":"2025-07-24T06:42:03+00:00","og_image":[{"width":835,"height":480,"url":"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1.jpg","type":"image\/jpeg"}],"author":"Cristina Castro","twitter_card":"summary_large_image","twitter_creator":"@FarmaIndustria","twitter_site":"@FarmaIndustria","twitter_misc":{"Escrito por":"Cristina Castro","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/#article","isPartOf":{"@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/"},"author":{"name":"Cristina Castro","@id":"https:\/\/www.farmaindustria.es\/web\/#\/schema\/person\/77de9caeaf35fd35feb9dec730e79595"},"headline":"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario","datePublished":"2025-07-11T10:00:09+00:00","dateModified":"2025-07-24T06:42:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/"},"wordCount":858,"commentCount":0,"image":{"@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/","url":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/","name":"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario - FarmaIndustria","isPartOf":{"@id":"https:\/\/www.farmaindustria.es\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/#primaryimage"},"image":{"@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1.jpg","datePublished":"2025-07-11T10:00:09+00:00","dateModified":"2025-07-24T06:42:03+00:00","author":{"@id":"https:\/\/www.farmaindustria.es\/web\/#\/schema\/person\/77de9caeaf35fd35feb9dec730e79595"},"breadcrumb":{"@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/#primaryimage","url":"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1.jpg","contentUrl":"https:\/\/www.farmaindustria.es\/web\/wp-content\/uploads\/sites\/2\/2025\/07\/En-salud-no-sin-mujeres1.jpg","width":835,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/2025\/07\/11\/nace-ensaludnosinmujeres-una-iniciativa-para-impulsar-el-liderazgo-y-la-visibilidad-femenina-en-el-ambito-sanitario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.farmaindustria.es\/web\/"},{"@type":"ListItem","position":2,"name":"Nace #EnSaludNoSinMujeres, una iniciativa para impulsar el liderazgo y la visibilidad femenina en el \u00e1mbito sanitario"}]},{"@type":"WebSite","@id":"https:\/\/www.farmaindustria.es\/web\/#website","url":"https:\/\/www.farmaindustria.es\/web\/","name":"FarmaIndustria","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.farmaindustria.es\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.farmaindustria.es\/web\/#\/schema\/person\/77de9caeaf35fd35feb9dec730e79595","name":"Cristina Castro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/aca4ecc9f65b97ba4366a217870b7ab4201d8e8f678c45221d982b892ff1cd7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aca4ecc9f65b97ba4366a217870b7ab4201d8e8f678c45221d982b892ff1cd7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aca4ecc9f65b97ba4366a217870b7ab4201d8e8f678c45221d982b892ff1cd7c?s=96&d=mm&r=g","caption":"Cristina Castro"},"url":"https:\/\/www.farmaindustria.es\/web\/prensa\/notas-de-prensa\/author\/ccastro\/"}]}},"_links":{"self":[{"href":"https:\/\/www.farmaindustria.es\/web\/wp-json\/wp\/v2\/posts\/22564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.farmaindustria.es\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.farmaindustria.es\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.farmaindustria.es\/web\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.farmaindustria.es\/web\/wp-json\/wp\/v2\/comments?post=22564"}],"version-history":[{"count":2,"href":"https:\/\/www.farmaindustria.es\/web\/wp-json\/wp\/v2\/posts\/22564\/revisions"}],"predecessor-version":[{"id":22643,"href":"https:\/\/www.farmaindustria.es\/web\/wp-json\/wp\/v2\/posts\/22564\/revisions\/22643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.farmaindustria.es\/web\/wp-json\/wp\/v2\/media\/22567"}],"wp:attachment":[{"href":"https:\/\/www.farmaindustria.es\/web\/wp-json\/wp\/v2\/media?parent=22564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}